{"id":10,"date":"2022-05-28T19:06:56","date_gmt":"2022-05-28T23:06:56","guid":{"rendered":"https:\/\/ediciones.uahurtado.cl\/my-account\/"},"modified":"2026-05-20T04:45:45","modified_gmt":"2026-05-20T08:45:45","slug":"myaccount","status":"publish","type":"page","link":"https:\/\/ediciones.uahurtado.cl\/en\/micuenta\/","title":{"rendered":"My Account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mi Cuenta - Ediciones UAH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ediciones.uahurtado.cl\/en\/myaccount\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mi Cuenta - Ediciones UAH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ediciones.uahurtado.cl\/en\/myaccount\/\" \/>\n<meta property=\"og:site_name\" content=\"Ediciones UAH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/edicionesuah?_rdc=2&amp;_rdr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T08:45:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/micuenta\\\/\",\"url\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/micuenta\\\/\",\"name\":\"Mi Cuenta - Ediciones UAH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/#website\"},\"datePublished\":\"2022-05-28T23:06:56+00:00\",\"dateModified\":\"2026-05-20T08:45:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/micuenta\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ediciones.uahurtado.cl\\\/micuenta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/micuenta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mi Cuenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/#website\",\"url\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/\",\"name\":\"Ediciones UAH\",\"description\":\"Universidad Alberto Hurtado\",\"publisher\":{\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/#organization\",\"name\":\"Ediciones UAH\",\"url\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-ediciones-UAH.png\",\"contentUrl\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-ediciones-UAH.png\",\"width\":584,\"height\":128,\"caption\":\"Ediciones UAH\"},\"image\":{\"@id\":\"https:\\\/\\\/ediciones.uahurtado.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/edicionesuah?_rdc=2&_rdr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"My Account - UAH Editions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ediciones.uahurtado.cl\/en\/myaccount\/","og_locale":"en_US","og_type":"article","og_title":"Mi Cuenta - Ediciones UAH","og_url":"https:\/\/ediciones.uahurtado.cl\/en\/myaccount\/","og_site_name":"Ediciones UAH","article_publisher":"https:\/\/www.facebook.com\/edicionesuah?_rdc=2&_rdr","article_modified_time":"2026-05-20T08:45:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ediciones.uahurtado.cl\/micuenta\/","url":"https:\/\/ediciones.uahurtado.cl\/micuenta\/","name":"My Account - UAH Editions","isPartOf":{"@id":"https:\/\/ediciones.uahurtado.cl\/#website"},"datePublished":"2022-05-28T23:06:56+00:00","dateModified":"2026-05-20T08:45:45+00:00","breadcrumb":{"@id":"https:\/\/ediciones.uahurtado.cl\/micuenta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ediciones.uahurtado.cl\/micuenta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ediciones.uahurtado.cl\/micuenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ediciones.uahurtado.cl\/"},{"@type":"ListItem","position":2,"name":"Mi Cuenta"}]},{"@type":"WebSite","@id":"https:\/\/ediciones.uahurtado.cl\/#website","url":"https:\/\/ediciones.uahurtado.cl\/","name":"UAH Editions","description":"Alberto Hurtado University","publisher":{"@id":"https:\/\/ediciones.uahurtado.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ediciones.uahurtado.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ediciones.uahurtado.cl\/#organization","name":"UAH Editions","url":"https:\/\/ediciones.uahurtado.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ediciones.uahurtado.cl\/#\/schema\/logo\/image\/","url":"https:\/\/ediciones.uahurtado.cl\/wp-content\/uploads\/2022\/06\/logo-ediciones-UAH.png","contentUrl":"https:\/\/ediciones.uahurtado.cl\/wp-content\/uploads\/2022\/06\/logo-ediciones-UAH.png","width":584,"height":128,"caption":"Ediciones UAH"},"image":{"@id":"https:\/\/ediciones.uahurtado.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/edicionesuah?_rdc=2&_rdr"]}]}},"_links":{"self":[{"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":4,"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":24799,"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/pages\/10\/revisions\/24799"}],"wp:attachment":[{"href":"https:\/\/ediciones.uahurtado.cl\/en\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}